{"id":2956,"date":"2018-03-16T09:26:10","date_gmt":"2018-03-16T08:26:10","guid":{"rendered":"https:\/\/www.prodevision.com\/blog\/?p=2956"},"modified":"2018-03-16T09:29:43","modified_gmt":"2018-03-16T08:29:43","slug":"debes-saber-acerca-lentillas-online","status":"publish","type":"post","link":"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/","title":{"rendered":"Todo lo que debes saber acerca de las lentillas online"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Los lentes de contacto o <a href=\"https:\/\/www.prodevision.com\">lentillas\u00a0online<\/a> cumplen la misma funci\u00f3n de las gafas para la vista<\/strong>; modifican la luz y la redirigen hacia la retina para proporcionar una visi\u00f3n m\u00e1s n\u00edtida.<\/p>\n<p style=\"text-align: justify;\">\u00c9stas son utilizadas para corregir distintos problemas que afectan la visi\u00f3n, tales como miop\u00eda, hipermetrop\u00eda, astigmatismo o presbicia y est\u00e1n fabricadas con diferentes materiales, las m\u00e1s comunes son las lentillas blandas que est\u00e1n fabricadas con silicona o hidrogel y permiten la oxigenaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><strong>Las lentillas pueden usarse por salud o est\u00e9tica y son muy pr\u00e1cticas al momento de hacer actividades deportivas<\/strong> y en comparaci\u00f3n con las gafas, las lentes de contacto permiten un campo visual m\u00e1s amplio.<\/p>\n<h3 style=\"text-align: justify;\">Cosas que debes tener en cuenta con respecto a las lentes de contacto<\/h3>\n<p style=\"text-align: justify;\">Al principio las lentillas pueden ser inc\u00f3modas y un poco exigentes en cuanto a mantenimiento e higiene, pero todo es cuesti\u00f3n de costumbre.<\/p>\n<p style=\"text-align: justify;\">Para el uso, cuidado y mantenimiento es importante que sigas todas instrucciones que trae la caja y las instrucciones dadas por el m\u00e9dico, de lo contrario, podr\u00edas contraer una infecci\u00f3n ocular; nunca debes lavar las lentilla con el agua del grifo, alcohol o agua oxigenada, esto podr\u00eda afectar tu ojo gravemente.<\/p>\n<p style=\"text-align: justify;\"><strong>En cuanto a dureza y duraci\u00f3n de uso, las lentes de contacto son muy diversos<\/strong>: pueden ser duras, semiduras o blandas y de duraci\u00f3n de uso diaria, semanal o mensual.<\/p>\n<p style=\"text-align: justify;\">Dependiendo del diagn\u00f3stico de la condici\u00f3n de tu ojo, el doctor te recomendar\u00e1 el que m\u00e1s se adapte a tu caso y estilo de vida.<\/p>\n<p style=\"text-align: justify;\"><strong>No hay edad para usarlas.<\/strong> Es com\u00fan o\u00edr que ni\u00f1os y adolescentes no pueden llevarlas; sin embargo, es totalmente falso. El uso depende de la responsabilidad y necesidad del usuario.<\/p>\n<p style=\"text-align: justify;\">No tengas miedo: las lentillas no se pegan en el ojo ni se pierden en \u00e9l. Con el uso continuo del l\u00edquido especial que estos traen hay pocas probabilidades que se peguen en el ojo, as\u00ed mismo, es imposible que este se pierda detr\u00e1s del ojo.<\/p>\n<h3 style=\"text-align: justify;\">Recomendaciones al momento de comprar <a href=\"https:\/\/www.prodevision.com\">lentillas online<\/a><\/h3>\n<p style=\"text-align: justify;\">Lo primero que debes hacer antes de comprar lentes de contacto es ir a un especialista y definir las necesidades en cuanto a tus problemas de visi\u00f3n y el uso que vas a darles.<\/p>\n<p style=\"text-align: justify;\"><strong>Cuando compres <a href=\"https:\/\/www.prodevision.com\">lentillas online<\/a> debes asegurarte de la confiabilidad de la marca y del vendedor.<\/strong> Adem\u00e1s, a la hora de comprar lentes de contacto por internet, tambi\u00e9n es importante contar con una empresa que especifique todas las caracter\u00edsticas y condiciones del producto, as\u00ed como proporcionar un transporte fiable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los lentes de contacto o lentillas\u00a0online cumplen la misma funci\u00f3n de las gafas para la vista; modifican la luz y la redirigen hacia la retina para proporcionar una visi\u00f3n m\u00e1s n\u00edtida. \u00c9stas son utilizadas para corregir distintos problemas que afectan la visi\u00f3n, tales como miop\u00eda, hipermetrop\u00eda, astigmatismo o presbicia y est\u00e1n fabricadas con diferentes materiales,&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Todo lo que debes saber acerca de las lentillas online<\/title>\n<meta name=\"description\" content=\"Hay ciertos aspectos que debes conocer acerca de las lentillas, y m\u00e1s a la hora de adquirir lentillas online. Aqu\u00ed te contamos todos los detalles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prodevisi\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/\",\"url\":\"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/\",\"name\":\"Todo lo que debes saber acerca de las lentillas online\",\"isPartOf\":{\"@id\":\"https:\/\/prodevision.com\/blog\/#website\"},\"datePublished\":\"2018-03-16T08:26:10+00:00\",\"dateModified\":\"2018-03-16T08:29:43+00:00\",\"author\":{\"@id\":\"https:\/\/prodevision.com\/blog\/#\/schema\/person\/29c40eba04892534ec2b7110214874b4\"},\"description\":\"Hay ciertos aspectos que debes conocer acerca de las lentillas, y m\u00e1s a la hora de adquirir lentillas online. Aqu\u00ed te contamos todos los detalles.\",\"breadcrumb\":{\"@id\":\"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/prodevision.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo lo que debes saber acerca de las lentillas online\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prodevision.com\/blog\/#website\",\"url\":\"https:\/\/prodevision.com\/blog\/\",\"name\":\"Prodevisi\u00f3n\",\"description\":\"Gafas de sol baratas, gafas graduadas y lentillas.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prodevision.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/prodevision.com\/blog\/#\/schema\/person\/29c40eba04892534ec2b7110214874b4\",\"name\":\"Prodevisi\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/prodevision.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8fa23b48b8f3ba33d4580d682f0e91d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8fa23b48b8f3ba33d4580d682f0e91d6?s=96&d=mm&r=g\",\"caption\":\"Prodevisi\u00f3n\"},\"sameAs\":[\"https:\/\/prodevision.com\/es\",\"https:\/\/www.facebook.com\/OpticaProdevision\",\"https:\/\/twitter.com\/prodevision\"],\"url\":\"https:\/\/prodevision.com\/blog\/author\/prodevision\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo lo que debes saber acerca de las lentillas online","description":"Hay ciertos aspectos que debes conocer acerca de las lentillas, y m\u00e1s a la hora de adquirir lentillas online. Aqu\u00ed te contamos todos los detalles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/","twitter_misc":{"Escrito por":"Prodevisi\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/","url":"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/","name":"Todo lo que debes saber acerca de las lentillas online","isPartOf":{"@id":"https:\/\/prodevision.com\/blog\/#website"},"datePublished":"2018-03-16T08:26:10+00:00","dateModified":"2018-03-16T08:29:43+00:00","author":{"@id":"https:\/\/prodevision.com\/blog\/#\/schema\/person\/29c40eba04892534ec2b7110214874b4"},"description":"Hay ciertos aspectos que debes conocer acerca de las lentillas, y m\u00e1s a la hora de adquirir lentillas online. Aqu\u00ed te contamos todos los detalles.","breadcrumb":{"@id":"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prodevision.com\/blog\/debes-saber-acerca-lentillas-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/prodevision.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Todo lo que debes saber acerca de las lentillas online"}]},{"@type":"WebSite","@id":"https:\/\/prodevision.com\/blog\/#website","url":"https:\/\/prodevision.com\/blog\/","name":"Prodevisi\u00f3n","description":"Gafas de sol baratas, gafas graduadas y lentillas.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodevision.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/prodevision.com\/blog\/#\/schema\/person\/29c40eba04892534ec2b7110214874b4","name":"Prodevisi\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prodevision.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8fa23b48b8f3ba33d4580d682f0e91d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fa23b48b8f3ba33d4580d682f0e91d6?s=96&d=mm&r=g","caption":"Prodevisi\u00f3n"},"sameAs":["https:\/\/prodevision.com\/es","https:\/\/www.facebook.com\/OpticaProdevision","https:\/\/twitter.com\/prodevision"],"url":"https:\/\/prodevision.com\/blog\/author\/prodevision\/"}]}},"_links":{"self":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts\/2956"}],"collection":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/comments?post=2956"}],"version-history":[{"count":2,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts\/2956\/revisions"}],"predecessor-version":[{"id":2959,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts\/2956\/revisions\/2959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/media\/2957"}],"wp:attachment":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/media?parent=2956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/categories?post=2956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/tags?post=2956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}