{"id":1768,"date":"2016-11-04T12:56:30","date_gmt":"2016-11-04T11:56:30","guid":{"rendered":"http:\/\/www.prodevision.com\/blog\/?p=1768"},"modified":"2019-07-12T19:46:51","modified_gmt":"2019-07-12T17:46:51","slug":"lentes-de-contacto-para-ninos","status":"publish","type":"post","link":"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/","title":{"rendered":"Lentes de contacto para ni\u00f1os, el complemento a las gafas"},"content":{"rendered":"<p>La adaptaci\u00f3n de lentes de contacto para ni\u00f1os es cada vez m\u00e1s frecuente, a pesar de la pol\u00e9mica creada alrededor de este tema, debido a las dificultades de manejo que se suelen presentar.<\/p>\n<p>Los resultados por parte de los ni\u00f1os, en la mayor\u00eda de los casos son fant\u00e1sticos, en cuanto a visi\u00f3n y est\u00e9tica.<\/p>\n<p>Hay casos en los que las lentes de contacto para ni\u00f1os est\u00e1n muy indicadas:<\/p>\n<ul>\n<li>Altas y medias miop\u00edas, en las que la visi\u00f3n con lentillas es mejor, haciendo que las im\u00e1genes en la retina sean m\u00e1s n\u00edtidas y de mayor tama\u00f1o que las que pueden proporcionar unas gafas graduadas.<\/li>\n<li>Diferencias importantes de graduaci\u00f3n entre un ojo y otro, son las llamadas anisometrop\u00edas. En ellas, la visi\u00f3n con la refracci\u00f3n \u00edntegra usando lentes de contacto para ni\u00f1os, tiene m\u00e1s tolerancia cerebral, haciendo que ambos ojos desarrollen la visi\u00f3n por igual.<\/li>\n<\/ul>\n<p>\u00bfCual es el mayor problema o dificultad que podemos encontrarnos al adaptar lentes de contacto para ni\u00f1os?<\/p>\n<p>Los ni\u00f1os tienen que aprender a pon\u00e9rselas, quit\u00e1rselas y el mantenimiento, a veces es necesaria la colaboraci\u00f3n de los padres, sobre todo en edades muy tempranas ( a veces se adaptan a beb\u00e9s).<\/p>\n<p>Lo \u00fanico que se necesita es un \u00f3ptico, adaptador de lentes de contacto para ni\u00f1os, mucha paciencia y muchas sesiones de aprendizaje, generalmente, los ni\u00f1os reaccionan muy bien y nos sorprenden con su habilidad.<\/p>\n<p>El horario de uso suele ser m\u00e1s reducido, limit\u00e1ndose a 8-10 horas al d\u00eda, descansando a mediod\u00eda a ser posible.<\/p>\n<p>Los reemplazos m\u00e1s utilizados en las <a href=\"https:\/\/www.prodevision.com\/es\/lentillas\">lentes de contacto<\/a> suelen ser dos:<\/p>\n<ul>\n<li><strong>Lentillas diarias:<\/strong> Se empiezan por la ma\u00f1ana y se tiran por la noche. Son ideales para liberar a los ni\u00f1os de las gafas a la hora de realizar actividades deportivas, baile&#8230; No necesitan mantenimiento ni limpieza. Se recomienda para un uso de dos o tres veces a la semana.<img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1774\" src=\"http:\/\/www.prodevision.com\/blog\/wp-content\/uploads\/2016\/11\/Lentes-de-contacto-para-ni\u00f1os-2-300x168.jpg\" alt=\"lentes de contacto para ni\u00f1os\" width=\"300\" height=\"168\" srcset=\"https:\/\/prodevision.com\/blog\/wp-content\/uploads\/2016\/11\/Lentes-de-contacto-para-ni\u00f1os-2-300x168.jpg 300w, https:\/\/prodevision.com\/blog\/wp-content\/uploads\/2016\/11\/Lentes-de-contacto-para-ni\u00f1os-2.jpg 590w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/li>\n<li><strong>Lentillas mensuales:<\/strong> Est\u00e1n indicadas para un uso diario, con control de horas, desech\u00e1ndose al mes de abrirlas, las hayamos usado m\u00e1s o menos. Requieren limpieza y mantenimiento. Est\u00e1n recomendadas para ni\u00f1os miopes o con hipermetrop\u00edas medias o altas.<img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1777\" src=\"http:\/\/www.prodevision.com\/blog\/wp-content\/uploads\/2016\/11\/Lentes-de-contacto-para-ni\u00f1os-3-300x168.jpg\" alt=\"lentes-de-contacto-para-ninos\" width=\"300\" height=\"168\" srcset=\"https:\/\/prodevision.com\/blog\/wp-content\/uploads\/2016\/11\/Lentes-de-contacto-para-ni\u00f1os-3-300x168.jpg 300w, https:\/\/prodevision.com\/blog\/wp-content\/uploads\/2016\/11\/Lentes-de-contacto-para-ni\u00f1os-3.jpg 590w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/li>\n<\/ul>\n<p>En Prodevisi\u00f3n somos profesionales de la visi\u00f3n, si tienes dudas, ll\u00e1manos o ponte en contacto con nosotros en nuestro correo electr\u00f3nico info@prodevision.com estaremos encantados de atenderte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La adaptaci\u00f3n de lentes de contacto para ni\u00f1os es cada vez m\u00e1s frecuente, a pesar de la pol\u00e9mica creada alrededor de este tema, debido a las dificultades de manejo que se suelen presentar. Los resultados por parte de los ni\u00f1os, en la mayor\u00eda de los casos son fant\u00e1sticos, en cuanto a visi\u00f3n y est\u00e9tica. Hay&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,47,32,29],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lentes de contacto para ni\u00f1os<\/title>\n<meta name=\"description\" content=\"En nuestra tienda online puedes comprar lentes de contacto para ni\u00f1os baratas, de primera marca y con la atenci\u00f3n de profesionales \u00f3pticos a tu disposici\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prodevisi\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/\",\"url\":\"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/\",\"name\":\"Lentes de contacto para ni\u00f1os\",\"isPartOf\":{\"@id\":\"https:\/\/prodevision.com\/blog\/#website\"},\"datePublished\":\"2016-11-04T11:56:30+00:00\",\"dateModified\":\"2019-07-12T17:46:51+00:00\",\"author\":{\"@id\":\"https:\/\/prodevision.com\/blog\/#\/schema\/person\/cc782ae54e013419e484f9121aa70666\"},\"description\":\"En nuestra tienda online puedes comprar lentes de contacto para ni\u00f1os baratas, de primera marca y con la atenci\u00f3n de profesionales \u00f3pticos a tu disposici\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/prodevision.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lentes de contacto para ni\u00f1os, el complemento a las gafas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prodevision.com\/blog\/#website\",\"url\":\"https:\/\/prodevision.com\/blog\/\",\"name\":\"Prodevisi\u00f3n\",\"description\":\"Gafas de sol baratas, gafas graduadas y lentillas.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prodevision.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/prodevision.com\/blog\/#\/schema\/person\/cc782ae54e013419e484f9121aa70666\",\"name\":\"Prodevisi\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/prodevision.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/307f137a0726793e89f2d1fd854acaa9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/307f137a0726793e89f2d1fd854acaa9?s=96&d=mm&r=g\",\"caption\":\"Prodevisi\u00f3n\"},\"sameAs\":[\"https:\/\/prodevision.com\/es\"],\"url\":\"https:\/\/prodevision.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lentes de contacto para ni\u00f1os","description":"En nuestra tienda online puedes comprar lentes de contacto para ni\u00f1os baratas, de primera marca y con la atenci\u00f3n de profesionales \u00f3pticos a tu disposici\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/","twitter_misc":{"Escrito por":"Prodevisi\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/","url":"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/","name":"Lentes de contacto para ni\u00f1os","isPartOf":{"@id":"https:\/\/prodevision.com\/blog\/#website"},"datePublished":"2016-11-04T11:56:30+00:00","dateModified":"2019-07-12T17:46:51+00:00","author":{"@id":"https:\/\/prodevision.com\/blog\/#\/schema\/person\/cc782ae54e013419e484f9121aa70666"},"description":"En nuestra tienda online puedes comprar lentes de contacto para ni\u00f1os baratas, de primera marca y con la atenci\u00f3n de profesionales \u00f3pticos a tu disposici\u00f3n.","breadcrumb":{"@id":"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prodevision.com\/blog\/lentes-de-contacto-para-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/prodevision.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Lentes de contacto para ni\u00f1os, el complemento a las gafas"}]},{"@type":"WebSite","@id":"https:\/\/prodevision.com\/blog\/#website","url":"https:\/\/prodevision.com\/blog\/","name":"Prodevisi\u00f3n","description":"Gafas de sol baratas, gafas graduadas y lentillas.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodevision.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/prodevision.com\/blog\/#\/schema\/person\/cc782ae54e013419e484f9121aa70666","name":"Prodevisi\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prodevision.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/307f137a0726793e89f2d1fd854acaa9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/307f137a0726793e89f2d1fd854acaa9?s=96&d=mm&r=g","caption":"Prodevisi\u00f3n"},"sameAs":["https:\/\/prodevision.com\/es"],"url":"https:\/\/prodevision.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts\/1768"}],"collection":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/comments?post=1768"}],"version-history":[{"count":13,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts\/1768\/revisions"}],"predecessor-version":[{"id":3253,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts\/1768\/revisions\/3253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/media\/1773"}],"wp:attachment":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/media?parent=1768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/categories?post=1768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/tags?post=1768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}