{"id":1003,"date":"2015-12-17T12:35:15","date_gmt":"2015-12-17T11:35:15","guid":{"rendered":"http:\/\/www.prodevision.com\/blog\/?p=1003"},"modified":"2019-07-17T11:23:38","modified_gmt":"2019-07-17T09:23:38","slug":"gafas-redondas","status":"publish","type":"post","link":"https:\/\/prodevision.com\/blog\/gafas-redondas\/","title":{"rendered":"Gafas Redondas, vuelve la moda retro en todo su esplendor"},"content":{"rendered":"<p>Las gafas redondas, tanto de sol como de graduado, est\u00e1n teniendo una gran presencia \u00faltimamente en las nuevas colecciones de los grandes dise\u00f1adores como Armani, Dior, Gucci, Marc Jacobs..etc.<\/p>\n<p>El estilo de gafas redondas que se lleva en estos momentos es en versiones peque\u00f1as \u00a0y vintage, incorporando variedad de colores y materiales, creando colecciones incre\u00edbles llenas de glamour.<\/p>\n<p>Este estilo de <a href=\"https:\/\/www.prodevision.com\/es\/gafas-de-sol\">gafas de sol<\/a> y graduadas se hizo mundialmente famoso gracias al compositor y beatle <strong>Jonh Lennon<\/strong>, inmortaliz\u00e1ndolas con miles de fotos y videos.<\/p>\n<p>Las gafas redondas se han mantenido ocultas durante varias d\u00e9cadas pero \u00faltimamente han aparecido de forma t\u00edmida el pasarelas y famosas que se animan a cualquier cosa, pero esta tendencia se est\u00e1 extendiendo en la calle y cada vez m\u00e1s podemos verlas entre nosotros.<\/p>\n<p>En Prodevisi\u00f3n, \u00f3ptica online, podr\u00e1s encontrar todos los modelos en gafas de sol y graduadas con forma redonda de los grandes dise\u00f1adores.<\/p>\n<p>Como profesionales de la visi\u00f3n tenemos que decir que las gafas de sol no son solo un complemento est\u00e9tico, sino una protecci\u00f3n necesaria para los ojos , ya que, es muy importante la barrera ultravioleta ante los rayos del sol. Cada vez es mayor la filtraci\u00f3n de radiaciones perjudiciales para el ojo debido a la rotura de la capa de ozono.<\/p>\n<p>Los usuarios de lentillas tambi\u00e9n deben usarlas, como protecci\u00f3n ante objetos extra\u00f1os y para evitar que las lentes de contacto se sequen y provoquen problemas oculares serios.<\/p>\n<p>Nos queda recordar a dos sectores de la poblaci\u00f3n muy importantes, las personas mayores y los ni\u00f1os, los primeros para evitar la evoluci\u00f3n de cataratas y problemas de retina y los ni\u00f1os porque est\u00e1n en pleno desarrollo de la visi\u00f3n y los rayos ultravioleta pueden generar da\u00f1os irreversibles para toda la vida.<\/p>\n<p><a href=\"https:\/\/www.prodevision.com\/blog\/wp-content\/uploads\/2015\/12\/3447.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-1011 size-medium\" title=\"Gafas Redondas\" src=\"https:\/\/www.prodevision.com\/blog\/wp-content\/uploads\/2015\/12\/3447-300x150.jpg\" alt=\"Gafas redondas\" width=\"300\" height=\"150\" srcset=\"https:\/\/prodevision.com\/blog\/wp-content\/uploads\/2015\/12\/3447-300x150.jpg 300w, https:\/\/prodevision.com\/blog\/wp-content\/uploads\/2015\/12\/3447.jpg 660w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Y volviendo a tema que nos ocupa, habr\u00e9is observado que las gafas redondas est\u00e1n de moda, as\u00ed que, atr\u00e9vete! entra en nuestra tienda online y no seas el \u00faltimo en comprar gafas de sol o <a href=\"https:\/\/www.prodevision.com\/es\/gafas-graduadas\">gafas graduadas<\/a> redondas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las gafas redondas, tanto de sol como de graduado, est\u00e1n teniendo una gran presencia \u00faltimamente en las nuevas colecciones de los grandes dise\u00f1adores como Armani, Dior, Gucci, Marc Jacobs..etc. El estilo de gafas redondas que se lleva en estos momentos es en versiones peque\u00f1as \u00a0y vintage, incorporando variedad de colores y materiales, creando colecciones incre\u00edbles&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1010,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,25,28,2],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gafas Redondas, vuelve la moda retro.<\/title>\n<meta name=\"description\" content=\"En Prodevisi\u00f3n tienda online disponemos de gafas redondas baratas de los mejores y m\u00e1s famosos dise\u00f1adores, aut\u00e9nticas, pago seguro y profesionalidad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodevision.com\/blog\/gafas-redondas\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prodevisi\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prodevision.com\/blog\/gafas-redondas\/\",\"url\":\"https:\/\/prodevision.com\/blog\/gafas-redondas\/\",\"name\":\"Gafas Redondas, vuelve la moda retro.\",\"isPartOf\":{\"@id\":\"https:\/\/prodevision.com\/blog\/#website\"},\"datePublished\":\"2015-12-17T11:35:15+00:00\",\"dateModified\":\"2019-07-17T09:23:38+00:00\",\"author\":{\"@id\":\"https:\/\/prodevision.com\/blog\/#\/schema\/person\/cc782ae54e013419e484f9121aa70666\"},\"description\":\"En Prodevisi\u00f3n tienda online disponemos de gafas redondas baratas de los mejores y m\u00e1s famosos dise\u00f1adores, aut\u00e9nticas, pago seguro y profesionalidad\",\"breadcrumb\":{\"@id\":\"https:\/\/prodevision.com\/blog\/gafas-redondas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prodevision.com\/blog\/gafas-redondas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/prodevision.com\/blog\/gafas-redondas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/prodevision.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gafas Redondas, vuelve la moda retro en todo su esplendor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prodevision.com\/blog\/#website\",\"url\":\"https:\/\/prodevision.com\/blog\/\",\"name\":\"Prodevisi\u00f3n\",\"description\":\"Gafas de sol baratas, gafas graduadas y lentillas.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prodevision.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/prodevision.com\/blog\/#\/schema\/person\/cc782ae54e013419e484f9121aa70666\",\"name\":\"Prodevisi\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/prodevision.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/307f137a0726793e89f2d1fd854acaa9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/307f137a0726793e89f2d1fd854acaa9?s=96&d=mm&r=g\",\"caption\":\"Prodevisi\u00f3n\"},\"sameAs\":[\"https:\/\/prodevision.com\/es\"],\"url\":\"https:\/\/prodevision.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gafas Redondas, vuelve la moda retro.","description":"En Prodevisi\u00f3n tienda online disponemos de gafas redondas baratas de los mejores y m\u00e1s famosos dise\u00f1adores, aut\u00e9nticas, pago seguro y profesionalidad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodevision.com\/blog\/gafas-redondas\/","twitter_misc":{"Escrito por":"Prodevisi\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prodevision.com\/blog\/gafas-redondas\/","url":"https:\/\/prodevision.com\/blog\/gafas-redondas\/","name":"Gafas Redondas, vuelve la moda retro.","isPartOf":{"@id":"https:\/\/prodevision.com\/blog\/#website"},"datePublished":"2015-12-17T11:35:15+00:00","dateModified":"2019-07-17T09:23:38+00:00","author":{"@id":"https:\/\/prodevision.com\/blog\/#\/schema\/person\/cc782ae54e013419e484f9121aa70666"},"description":"En Prodevisi\u00f3n tienda online disponemos de gafas redondas baratas de los mejores y m\u00e1s famosos dise\u00f1adores, aut\u00e9nticas, pago seguro y profesionalidad","breadcrumb":{"@id":"https:\/\/prodevision.com\/blog\/gafas-redondas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodevision.com\/blog\/gafas-redondas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prodevision.com\/blog\/gafas-redondas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/prodevision.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Gafas Redondas, vuelve la moda retro en todo su esplendor"}]},{"@type":"WebSite","@id":"https:\/\/prodevision.com\/blog\/#website","url":"https:\/\/prodevision.com\/blog\/","name":"Prodevisi\u00f3n","description":"Gafas de sol baratas, gafas graduadas y lentillas.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodevision.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/prodevision.com\/blog\/#\/schema\/person\/cc782ae54e013419e484f9121aa70666","name":"Prodevisi\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prodevision.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/307f137a0726793e89f2d1fd854acaa9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/307f137a0726793e89f2d1fd854acaa9?s=96&d=mm&r=g","caption":"Prodevisi\u00f3n"},"sameAs":["https:\/\/prodevision.com\/es"],"url":"https:\/\/prodevision.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts\/1003"}],"collection":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/comments?post=1003"}],"version-history":[{"count":16,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts\/1003\/revisions"}],"predecessor-version":[{"id":3280,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/posts\/1003\/revisions\/3280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/media\/1010"}],"wp:attachment":[{"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/media?parent=1003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/categories?post=1003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prodevision.com\/blog\/wp-json\/wp\/v2\/tags?post=1003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}